{"id":9277,"date":"2023-09-07T17:08:04","date_gmt":"2023-09-07T15:08:04","guid":{"rendered":"https:\/\/bk1.myalb.it\/hoteliaccarino.it\/it\/?page_id=9277"},"modified":"2023-11-28T10:26:03","modified_gmt":"2023-11-28T09:26:03","slug":"rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs","status":"publish","type":"page","link":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/","title":{"rendered":"Rooms De Luxe EN"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9277\" class=\"elementor elementor-9277\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4fb756 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"d4fb756\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7cea58\" data-id=\"e7cea58\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eed849 elementor-widget elementor-widget-heading\" data-id=\"4eed849\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sea view Deluxe room with balcony <br>Comfort e Relax<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46485ef elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"46485ef\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bbe024\" data-id=\"1bbe024\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73994e4 elementor-widget elementor-widget-shortcode\" data-id=\"73994e4\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script>\r\n\tvar $jj = jQuery.noConflict();\r\n\t$jj(function()\r\n\t{\r\n\t\t\t\t$jj.datepicker.regional['it'] = {\r\n\t\t\t\t\tcloseText: 'Chiudi', \/\/ set a close button text\r\n\t\t\t    currentText: 'Oggi', \/\/ set today text\r\n\t\t\t    monthNames: ['Gennaio','Febbraio','Marzo','Aprile','Maggio','Giugno',   'Luglio','Agosto','Settembre','Ottobre','Novembre','Dicembre'], \/\/ set month names\r\n\t\t\t    monthNamesShort: ['Gen','Feb','Mar','Apr','Mag','Giu','Lug','Ago','Set','Ott','Nov','Dic'], \/\/ set short month names\r\n\t\t\t    dayNames: ['Domenica','Luned&#236','Marted&#236','Mercoled&#236','Gioved&#236','Venerd&#236','Sabato'], \/\/ set days names\r\n\t\t\t    dayNamesShort: ['Dom','Lun','Mar','Mer','Gio','Ven','Sab'], \/\/ set short day names\r\n\t\t\t    dayNamesMin: ['Do','Lu','Ma','Me','Gio','Ve','Sa'], \/\/ set more short days names\r\n\t\t\t    dateFormat: 'dd\/mm\/yy' \/\/ set format date\r\n\t\t\t\t};\r\n\t\t$jj.datepicker.setDefaults($jj.datepicker.regional['it']);\r\n\t\t$jj( \"#dataIn\" ).datepicker({\r\n\t\t\t\tdateFormat: \"dd-mm-yy\",\/\/per la lingua  inglese: \"yy-mm-dd\"\r\n\t\t\t\tminDate: new Date(2026, 05 - 1, 13),\r\n\t\t\t\tonClose: function() { setPartenza() }\r\n\t\t\t});\r\n\t\t$jj( \"#dataOut\" ).datepicker({\r\n\t\t\t  regional: \"IT\",\r\n\t\t\t\tdateFormat: \"dd-mm-yy\",\/\/per la lingua  inglese: \"yy-mm-dd\"\r\n\t\t\t\tminDate: new Date(2026, 05 - 1, 13)\r\n\t\t\t});\r\n\t});\r\n\r\n\r\n\tfunction Obbligatorio()\r\n\t{\r\n\t\tcontrolla('frmRicercaDisponibilitaPortale');\r\n\t};\r\n\/\/javascript:controlla(\".'\"frmRicercaDisponibilitaPortale\"'.\");\r\n<\/script>\r\n<script type=\"text\/javascript\">\r\n\tfunction setPartenza()\r\n\t{\r\n\t\tDate.prototype.addDays = function(intDays) {this.setDate(this.getDate() + intDays);}\r\n\t\tdataArrivo = document.getElementById(\"dataIn\").value;\r\n\t\tdA = dataArrivo.split(\"-\");\r\n\r\n\t\tif('it'=='it')\r\n\t\t\tdata = new Date(dA[1]+\"\/\"+dA[0]+\"\/\"+dA[2]);\r\n\t\telse\r\n\t\t\tdata = new Date(dA[1]+\"\/\"+dA[2]+\"\/\"+dA[0]);\r\n\r\n\t\tdata.addDays(1);\r\n\r\n\t\tif(data.getDate()<10) {\tdd = \"0\"+data.getDate(); } else\t{ dd = data.getDate(); }\r\n\t\tif(data.getMonth()<9) { mm = \"0\"+(data.getMonth()+1); } else { mm = data.getMonth()+1; }\r\n\r\n\t\tif('it'=='it')\r\n\t\t\tdocument.getElementById(\"dataOut\").value = dd+\"-\"+mm+\"-\"+data.getFullYear();\r\n\t\telse\r\n\t\t\tdocument.getElementById(\"dataOut\").value = data.getFullYear()+\"-\"+mm+\"-\"+dd;\r\n\t}\r\n\r\n\r\n\tfunction controlla(id)\r\n\t{\r\n\t\tvar form = document.getElementById(id);\r\n\t\tdataArr  = form.dataIn.value;\r\n\t\tdataPart = form.dataOut.value;\r\n\r\n\t\tdA = dataArr.split(\"-\");\r\n\t\tdP = dataPart.split(\"-\");\r\n\r\n\t\tif(dA[0].length < 2) { dA[0] = \"0\"+dA[0]; }\r\n\t\tif(dA[1].length < 2) { dA[1] = \"0\"+dA[1]; }\r\n\r\n\t\tdataArrivo   = dA[2]+dA[1]+dA[0];\r\n\t\tdataPartenza = dP[2]+dP[1]+dP[0];\r\n\r\n\t\tif(dataPartenza <= dataArrivo) {\r\n\t\t\talert(\"Attenzione! La data partenza deve essere superiore della data arrivo.\");\r\n\t\t  \treturn false;\r\n\t\t}\r\n\t\telse\r\n\t\t{\r\n\t\t\tform.submit();\r\n\t\t}\r\n\t}\r\n<\/script>\r\n\t\t<div class=\"elementor-shortcode\"><HTML> <meta name='viewport' content='width=device-width, initial-scale=1, minimum-scale=1, maximum-scale=1'><link href='https:\/\/www.hoteliaccarino.co.uk\/gb\/booking\/css\/book_form_date.css' rel='stylesheet' type='text\/css' media='all' \/>\r\n\t\t\t\t <link href='https:\/\/www.hoteliaccarino.co.uk\/gb\/booking\/css\/jquery-ui-1.10.4.custom.css' rel='stylesheet'>\r\n\t\t\t\t <script src='https:\/\/www.hoteliaccarino.co.uk\/gb\/booking\/js\/jquery-ui-1.10.4.custom.js'><\/script><div class='square-box'>\r\n    \t\t\t<div class='square-content'>\r\n\t\t\t\t\t\t<form target='_black' name='frmRicercaDisponibilitaPortale' id='frmRicercaDisponibilitaPortale' method='post' action='https:\/\/w1.myalb.it\/booking\/v5\/index.php' onSubmit='return controlla(this)'>\t\t\t<div id='booking-in'>\r\n\t \t\t\t\t\t\t\t<input type='hidden' name='hcid' value='67rd5f0f1m617585750b45c65678beg1'>\r\n\t\t\t          <input type='hidden' name='view' value='step1'>\r\n\t\t\t \t\t\t\t\t<input type='hidden' name='lang' value='en'>\r\n\t\t\t \t\t\t\t\t<span id='arrivo_trigger'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>Arrivo<\/label>--> <input type='text' name='dataIn' id='dataIn' size='10' readonly placeholder='Arrivo' value='14-05-2026'>&nbsp;<!--<img id='img-cal-a' src='images\/showcal.gif' align='absbottom'>-->\r\n\t\t\t\t\t\t\t\t<\/span>\r\n \t\t\t\t\t\t\t\t<span id='partenza_trigger'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>Partenza<\/label>--> <input type='text' name='dataOut' id='dataOut' size='10' placeholder='Partenza' readonly value='15-05-2026'>&nbsp;<!--<img id='img-cal-p' src='images\/showcal.gif' align='absbottom'>-->\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/div>\t\t\t<div id='blocco-destro'>\r\n\t\t\t\t\t\t\t\t<span id='persone'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>People<\/label>--><input type='number' id='adulti' name='adulti' placeholder='People per room' size='3' maxlength='2' max= '4' min='1' \/>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t<span id='book-search'>\r\n\t\t\t\t\t\t\t\t\t<a id='cerca' onclick='javascript:Obbligatorio();'>Check availability<\/a>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/div>\t\t<\/form>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/HTML><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38f9b1c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38f9b1c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9c780f6\" data-id=\"9c780f6\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ab667b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2ab667b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">double bed \/ two separate beds<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-487196c\" data-id=\"487196c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ee8a8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"81ee8a8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Private bathroom<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d3a5ef0\" data-id=\"d3a5ef0\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95c414d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"95c414d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Free Wifi<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-450ffe4\" data-id=\"450ffe4\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb05aec elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb05aec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Air conditioning<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a72b40c\" data-id=\"a72b40c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcb2ace elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fcb2ace\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:600,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 People<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed28c14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed28c14\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88e4398\" data-id=\"88e4398\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e49edcf elementor-widget elementor-widget-image\" data-id=\"e49edcf\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/04\/Hotel_a_Sorrento_Hotel_Jaccarino_camera_de_lux_verticale.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9b9fa03\" data-id=\"9b9fa03\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ef7921 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4ef7921\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comfort & Relax<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93fe4ae elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"93fe4ae\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">With the wonders <br>of St Agatha's<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-559a454 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"559a454\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Delicata fodera in organza blu ricamata trasparente con pieghe elasticizzate in misto acetato di lusso. Dettaglio in pelle spalla contrasto colore contorno splendida silhouette di lavoro peplo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6711da3 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6711da3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uk-margin\">double room with balcony, A\/C, Wi-Fi, Smart TV, safe, minibar, telephone, bath or shower, bathroom amenities, hairdryer, bathrobe, slippers, possibility of third and fourth bed, family room and connecting rooms.<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7019572 elementor-align-left elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"7019572\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/w1.myalb.it\/booking\/v5\/index.php?hcid=67rd5f0f1m617585750b45c65678beg1&#038;view=step1&#038;lang=en\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Book this room<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1af6789 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1af6789\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2473230\" data-id=\"2473230\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4627ee9 elementor-widget elementor-widget-hoteller-slider-parallax\" data-id=\"4627ee9\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-slider-parallax.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"slider_parallax_wrapper\" data-autoplay=\"0\" data-pagination=\"0\" data-navigation=\"1\">\n\t<div class=\"slider_parallax_inner\">\n\t\t<div class=\"slider_parallax_slides\">\n\t\t\t\t\t\t<div class=\"slide is-active \">\n\t\t          \t<div class=\"slide-content\">\n\t\t            \t<div class=\"caption\">\n\t\t\t\t\t\t\t<div class=\"title\"><h2><\/h2><\/div>\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t                \t\t\t\t              \t\t<\/div> \n\t\t\t                \t\t            \t<\/div>\n\t\t          \t<\/div>\n\t\t\t\t  \t<div class=\"image-container\"> \n\t\t            \t<img decoding=\"async\" src=\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_2.jpg\" alt=\"\" class=\"image\" \/>\n\t\t          \t<\/div>\n\t\t        <\/div>\n\t\t\t\t<\/div>\n\t\t\t    \t    <div class=\"arrows\">\n\t        <div class=\"arrow prev\">\n\t          <span class=\"svg svg-arrow-left\">\n\t            <svg version=\"1.1\" id=\"svg4-Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"14px\" height=\"26px\" viewBox=\"0 0 14 26\" enable-background=\"new 0 0 14 26\" xml:space=\"preserve\"> <path d=\"M13,26c-0.256,0-0.512-0.098-0.707-0.293l-12-12c-0.391-0.391-0.391-1.023,0-1.414l12-12c0.391-0.391,1.023-0.391,1.414,0s0.391,1.023,0,1.414L2.414,13l11.293,11.293c0.391,0.391,0.391,1.023,0,1.414C13.512,25.902,13.256,26,13,26z\"\/> <\/svg>\n\t            <span class=\"alt sr-only\"><\/span>\n\t          <\/span>\n\t        <\/div>\n\t        <div class=\"arrow next\">\n\t          <span class=\"svg svg-arrow-right\">\n\t            <svg version=\"1.1\" id=\"svg5-Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"14px\" height=\"26px\" viewBox=\"0 0 14 26\" enable-background=\"new 0 0 14 26\" xml:space=\"preserve\"> <path d=\"M1,0c0.256,0,0.512,0.098,0.707,0.293l12,12c0.391,0.391,0.391,1.023,0,1.414l-12,12c-0.391,0.391-1.023,0.391-1.414,0s-0.391-1.023,0-1.414L11.586,13L0.293,1.707c-0.391-0.391-0.391-1.023,0-1.414C0.488,0.098,0.744,0,1,0z\"\/> <\/svg>\n\t            <span class=\"alt sr-only\"><\/span>\n\t          <\/span>\n\t        <\/div>\n\t    <\/div>\n\t    \t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e24128d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e24128d\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3609f9c\" data-id=\"3609f9c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4cb799 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c4cb799\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Room features<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3732f9c elementor-widget elementor-widget-spacer\" data-id=\"3732f9c\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3799fbf elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3799fbf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Choice of (double bed) or (two separate beds).<br \/>Bathroom with bath or shower, hairdryer, magnifying mirror, selection of toiletries, bathrobes, slippers, pool\/sea towels.<br \/>Smart TV.<br \/>Wardrobe with safe.<br \/>Individual air conditioning from June to September.<br \/>Individual heating.<br \/>Direct dial telephone.<br \/>Minibar with charge.<br \/>Work desk.<br \/>Free wifi and internet access.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2019042 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2019042\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_pagina_home_3.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ecb69d7\" data-id=\"ecb69d7\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e47e9e8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e47e9e8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/04\/Hotel_a_Sorrento_Hotel_Jaccarino_camera_de_lux_verticale.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sea view Deluxe room with balcony Comfort e Relax double bed \/ two separate beds Private bathroom Free Wifi Air conditioning 2 People Comfort &#038; Relax With the wonders of St Agatha&#8217;s Delicata fodera in organza blu ricamata trasparente con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7839,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9277","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rooms De Luxe Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino<\/title>\n<meta name=\"description\" content=\"Rooms De Luxe Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rooms De Luxe Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino\" \/>\n<meta property=\"og:description\" content=\"Rooms De Luxe Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Iaccarino\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T09:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1499\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/\",\"url\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/\",\"name\":\"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino\",\"isPartOf\":{\"@id\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg\",\"datePublished\":\"2023-09-07T15:08:04+00:00\",\"dateModified\":\"2023-11-28T09:26:03+00:00\",\"description\":\"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage\",\"url\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg\",\"contentUrl\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg\",\"width\":1499,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hoteliaccarino.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rooms De Luxe EN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/#website\",\"url\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/\",\"name\":\"Hotel Iaccarino\",\"description\":\"Hotel a Sorrento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hoteliaccarino.co.uk\/gb\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","description":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/","og_locale":"it_IT","og_type":"article","og_title":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","og_description":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.","og_url":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/","og_site_name":"Hotel Iaccarino","article_modified_time":"2023-11-28T09:26:03+00:00","og_image":[{"width":1499,"height":1000,"url":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/","url":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/","name":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","isPartOf":{"@id":"https:\/\/www.hoteliaccarino.co.uk\/gb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage"},"image":{"@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg","datePublished":"2023-09-07T15:08:04+00:00","dateModified":"2023-11-28T09:26:03+00:00","description":"Rooms De Luxe Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. De Luxe rooms are equipped with numerous amenities.","breadcrumb":{"@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#primaryimage","url":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg","contentUrl":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_3.jpg","width":1499,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoteljaccarino.com\/gb\/rooms-de-luxe-hotel-sant-agata-on-the-two-gulfs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoteliaccarino.it\/it\/"},{"@type":"ListItem","position":2,"name":"Rooms De Luxe EN"}]},{"@type":"WebSite","@id":"https:\/\/www.hoteliaccarino.co.uk\/gb\/#website","url":"https:\/\/www.hoteliaccarino.co.uk\/gb\/","name":"Hotel Iaccarino","description":"Hotel a Sorrento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoteliaccarino.co.uk\/gb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/pages\/9277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/comments?post=9277"}],"version-history":[{"count":4,"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/pages\/9277\/revisions"}],"predecessor-version":[{"id":9516,"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/pages\/9277\/revisions\/9516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/media\/7839"}],"wp:attachment":[{"href":"https:\/\/www.hoteliaccarino.co.uk\/gb\/wp-json\/wp\/v2\/media?parent=9277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}